{"id":9296,"date":"2018-11-07T10:09:43","date_gmt":"2018-11-07T15:09:43","guid":{"rendered":"https:\/\/www.vayahealth.com\/?p=8436"},"modified":"2025-02-11T10:25:52","modified_gmt":"2025-02-11T15:25:52","slug":"outpatient-opioid-treatment-program-to-open-in-spindale-2","status":"publish","type":"post","link":"https:\/\/www.vayahealth.com\/es\/outpatient-opioid-treatment-program-to-open-in-spindale-2\/","title":{"rendered":"Se abrir\u00e1 en Spindale un programa de tratamiento ambulatorio contra los opi\u00e1ceos"},"content":{"rendered":"<p><strong><em>Los nuevos servicios cl\u00ednicos comenzar\u00e1n el 1 de enero de 2019<\/em><\/strong><\/p>\r\n\r\n\r\n\r\n<p>ASHEVILLE - Vaya Health y Blue Ridge Health (BRH) unen sus fuerzas para abrir un nuevo programa de tratamiento ambulatorio de la adicci\u00f3n a los opi\u00e1ceos en el condado de Rutherford.<\/p>\r\n\r\n\r\n\r\n<p>Se espera que los servicios de tratamiento de opioides basados en la oficina comiencen el 1 de enero de 2019 en la cl\u00ednica BRH en 187 W. Main St. en Spindale. El programa permitir\u00e1 a los m\u00e9dicos de atenci\u00f3n primaria proporcionar tratamiento asistido con medicaci\u00f3n en la cl\u00ednica para ayudar a combatir el aumento de la adicci\u00f3n a las drogas opioides, que incluyen hero\u00edna y muchos analg\u00e9sicos recetados, y el creciente n\u00famero de muertes por sobredosis a nivel local y nacional.<\/p>\r\n\r\n\r\n\r\n<p>Inicialmente, el programa atender\u00e1 a 60 residentes del condado de Rutherford. Es posible que se a\u00f1adan m\u00e1s plazas a medida que se desarrollen los servicios.<\/p>\r\n\r\n\r\n\r\n<p>Vaya, una organizaci\u00f3n p\u00fablica de atenci\u00f3n sanitaria gestionada, presta servicio a 32 condados del oeste de Carolina del Norte, incluido Rutherford. Vaya utilizar\u00e1 fondos de reinversi\u00f3n en la comunidad y subvenciones de la Ley 21st Century Cures para financiar el nuevo programa. BRH, un centro de salud federalmente cualificado, prestar\u00e1 una serie de servicios, como evaluaciones de consumo de sustancias, pruebas de laboratorio, asesoramiento individual y de grupo, atenci\u00f3n m\u00e9dica general y tratamiento psiqui\u00e1trico.<\/p>\r\n\r\n\r\n\r\n<p>Tras recibir formaci\u00f3n especializada, los proveedores de BRH podr\u00e1n recetar buprenorfina, un medicamento utilizado para tratar la adicci\u00f3n a los opi\u00e1ceos.<\/p>\r\n\r\n\r\n\r\n<p>\"Sabemos que la prevenci\u00f3n y el tratamiento del trastorno por consumo de opi\u00e1ceos es una de las principales prioridades del condado de Rutherford\", afirm\u00f3 Brian Ingraham, director general de Vaya. \"Esta asociaci\u00f3n nos permitir\u00e1 ofrecer un tratamiento de calidad aqu\u00ed mismo, en la comunidad local, de una manera que permita a las personas vivir en casa, estar cerca de la familia e incluso seguir trabajando o asistiendo a la escuela mientras reconstruyen sus vidas.\"<\/p>\r\n\r\n\r\n\r\n<p>El Dr. Richard Hudspeth, director general de BRH, ha declarado: \"Hemos observado resultados positivos con el tratamiento asistido con medicaci\u00f3n en nuestras otras consultas del oeste de Carolina del Norte, y estamos convencidos de que la aplicaci\u00f3n de este programa basado en pruebas en colaboraci\u00f3n con Vaya ayudar\u00e1 a abordar el grave problema del consumo de sustancias en el condado de Rutherford.\"<\/p>\r\n\r\n\r\n\r\n<p>Vaya tambi\u00e9n proporcionar\u00e1 servicios de coordinaci\u00f3n de la atenci\u00f3n para garantizar que los participantes reciban un tratamiento basado en sus necesidades individuales. Adem\u00e1s, Vaya proporcionar\u00e1 a la farmacia kits de eliminaci\u00f3n de opi\u00e1ceos para fomentar la eliminaci\u00f3n segura de los medicamentos no utilizados.<\/p>\r\n\r\n\r\n\r\n<p>Juntos, Vaya y BRH trabajar\u00e1n para garantizar un proceso de derivaci\u00f3n sencillo, mejorar el acceso a los servicios de salud conductual mejorando las conexiones con las partes interesadas del condado, ampliar el uso de datos para hacer un seguimiento de la necesidad de tratamiento y llevar a cabo campa\u00f1as de educaci\u00f3n y concienciaci\u00f3n de la comunidad.<\/p>\r\n\r\n\r\n\r\n<p>Para obtener m\u00e1s informaci\u00f3n sobre el programa de Spindale u otros servicios locales de consumo de sustancias, llame a la l\u00ednea gratuita de crisis de salud conductual del Vaya, que funciona las 24 horas del d\u00eda, los 7 d\u00edas de la semana, al 1-800-849-6127.<\/p>\r\n\r\n\r\n\r\n<p><strong>Acerca de Blue Ridge Community Health Services<br><\/strong>Blue Ridge Health (BRH) es un sistema sanitario sin \u00e1nimo de lucro que colabora estrechamente con las comunidades para satisfacer las cambiantes necesidades sanitarias de nuestra regi\u00f3n con servicios sanitarios de alta calidad, integrales y accesibles. Con 17 ubicaciones en todo el oeste de Carolina del Norte y programas adicionales dentro de las escuelas, BRH ofrece atenci\u00f3n primaria para adultos y ni\u00f1os, atenci\u00f3n durante el embarazo, farmacia, salud conductual, servicios dentales y de nutrici\u00f3n que priorizan la experiencia de atenci\u00f3n del paciente. Durante m\u00e1s de 55 a\u00f1os, BRH ha sido el l\u00edder en atenci\u00f3n sanitaria centrada en la comunidad, prestando servicios a las comunidades de los condados de Henderson, Rutherford, Buncombe, Transylvania, Polk, Jackson y Haywood. Si desea m\u00e1s informaci\u00f3n sobre Blue Ridge Health, llame al 828-692-4289 o visite <a href=\"http:\/\/www.brchs.com\">www.brchs.com<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>New clinic services set to begin on Jan. 1, 2019 ASHEVILLE \u2013 Vaya Health and Blue Ridge Health (BRH) are joining forces to open a new outpatient opioid addiction treatment [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":48863,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_tec_requires_first_save":true,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","banner-text":"","banner-text-color":"","button-text":"","button-text-color":"","button-link":"","has-button-icon":"","background-color":"","has-background-icon":"","background-icon-color":"","second-featured-image":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"categories":[34594],"tags":[],"class_list":["post-9296","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-substance-use-disorder"],"aioseo_notices":[],"ticketed":false,"_links":{"self":[{"href":"https:\/\/www.vayahealth.com\/es\/wp-json\/wp\/v2\/posts\/9296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vayahealth.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vayahealth.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vayahealth.com\/es\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vayahealth.com\/es\/wp-json\/wp\/v2\/comments?post=9296"}],"version-history":[{"count":0,"href":"https:\/\/www.vayahealth.com\/es\/wp-json\/wp\/v2\/posts\/9296\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vayahealth.com\/es\/wp-json\/wp\/v2\/media\/48863"}],"wp:attachment":[{"href":"https:\/\/www.vayahealth.com\/es\/wp-json\/wp\/v2\/media?parent=9296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vayahealth.com\/es\/wp-json\/wp\/v2\/categories?post=9296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vayahealth.com\/es\/wp-json\/wp\/v2\/tags?post=9296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}